{"id":1635,"title":{"rendered":"\u041c\u0430\u043a\u0456 \u0437 \u043a\u0440\u0435\u0432\u0435\u0442\u043a\u043e\u044e"},"content":{"rendered":""},"excerpt":{"rendered":"\u0440\u0438\u0441, \u043d\u043e\u0440\u0456, \u043a\u0440\u0435\u0432\u0435\u0442\u043a\u0430"},"product_brand":[],"product_cat":[29],"meta_data":{"price":"170.00","sku":"34808","sku2":"","width":"","weight":"120","proteins":"10.9","carbohydrates":"17.9","fat":"0.3","calories":"118","is_sushi":true,"sticks_count":1,"sell_from":null,"sell_to":null,"mob_img":"https:\/\/la.ua\/rivne\/wp-content\/uploads\/sites\/9\/2021\/08\/maki-krevetka_m.jpg","cat":"maky","gallery":["https:\/\/la.ua\/rivne\/wp-content\/uploads\/sites\/9\/2021\/08\/maki-krevetka_m.jpg"],"modifiers":[],"isSauce":false,"isDish":true,"enabled_sets":false,"hasDetail":true,"free_extenstions":{"soy_sauce":{"id":641376,"count":2},"wasabi":{"id":641375,"count":2},"ginger":{"id":641374,"count":2}}}}